{"id":18632,"date":"2025-11-13T13:46:30","date_gmt":"2025-11-13T05:46:30","guid":{"rendered":"https:\/\/web.ts.com.tw\/zh_tw\/?page_id=18632"},"modified":"2025-11-13T16:25:41","modified_gmt":"2025-11-13T08:25:41","slug":"1200v-low-loss-diode","status":"publish","type":"page","link":"http:\/\/www.taiwansemi.com\/zh_tw\/resources\/infographic\/1200v-low-loss-diode\/","title":{"rendered":"1200V Low-Loss Diodes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18632\" class=\"elementor elementor-18632\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01d956b e-flex e-con-boxed e-con e-parent\" data-id=\"01d956b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f17b4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a0f17b4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u7522\u54c1\u5716\u8b5c<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07aaa50 e-flex e-con-boxed e-con e-parent\" data-id=\"07aaa50\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0903d0 jet-breadcrumbs-on-front-yes jet-breadcrumbs-align-left breadcrumb-icon elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"a0903d0\" data-element_type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"http:\/\/www.taiwansemi.com\/zh_tw\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"\u9996\u9801\">\u9996\u9801<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5934c1 e-flex e-con-boxed e-con e-parent\" data-id=\"e5934c1\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;e4c8d12&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-acc87cf e-flex e-con-boxed e-con e-child\" data-id=\"acc87cf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5342bc7 elementor-widget elementor-widget-image\" data-id=\"5342bc7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/zh_tw\/wp-content\/uploads\/2025\/11\/tsc-taiwan-semiconductor-1200v-lld.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"405\" src=\"http:\/\/www.taiwansemi.com\/zh_tw\/wp-content\/uploads\/2025\/11\/tsc-taiwan-semiconductor-1200v-lld-720.jpg?ver=1764127202\" class=\"attachment-large size-large wp-image-18631\" alt=\"1200V Low-Loss Diodes Now Offered in High-Demand Package Options\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae24166 elementor-widget elementor-widget-text-editor\" data-id=\"ae24166\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u9ede\u64ca\u5716\u7247\u4ee5 PDF \u6a94\u6848\u700f\u89bd<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb94ea4 e-flex e-con-boxed e-con e-child\" data-id=\"fb94ea4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-799c1b3 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"799c1b3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/zh_tw\/wp-content\/uploads\/2025\/11\/tsc-taiwan-semiconductor-1200v-lld.pdf\" target=\"_blank\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u4e0b\u8f09<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efa6c1a elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"efa6c1a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/zh_tw\/product-filter\/?category=standard-rectifier-12&#038;conditions=N4IgLgpgxgFgdgewDYIOYE8QC5S2gawgBMB9BABzAEsE4BnbAbRAAUkBDOdgJxAF0AvgKA\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u7522\u54c1\u8a0a\u606f<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4007fac elementor-grid-mobile-0 elementor-share-buttons-mobile--align-left elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-hidden-mobile uael-share-buttons--view-icon-text uael-stylex-inline elementor-grid-0 elementor-widget elementor-widget-uael-social-share\" data-id=\"4007fac\" data-element_type=\"widget\" data-settings=\"{&quot;columns_mobile&quot;:&quot;0&quot;,&quot;alignment_mobile&quot;:&quot;left&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.85,&quot;sizes&quot;:[]},&quot;button_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.8,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;0&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"uael-style-inline uael-container uael-floating-align-\" data-pin_data_url=\"\" data-share_url_type=\"current_page\" data-share_url=\"\">\r\n\t\t\t<div class=\"elementor-grid uael-floating-align-\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-facebook\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-linkedin\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-email\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdcb93c uael-share-buttons--view-icon elementor-grid-mobile-0 elementor-share-buttons-mobile--align-center elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet uael-stylex-inline elementor-grid-0 elementor-widget elementor-widget-uael-social-share\" data-id=\"fdcb93c\" data-element_type=\"widget\" data-settings=\"{&quot;columns_mobile&quot;:&quot;0&quot;,&quot;alignment_mobile&quot;:&quot;center&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.85,&quot;sizes&quot;:[]},&quot;button_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.8,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;0&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"uael-style-inline uael-container uael-floating-align-\" data-pin_data_url=\"\" data-share_url_type=\"current_page\" data-share_url=\"\">\r\n\t\t\t<div class=\"elementor-grid uael-floating-align-\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-facebook\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-linkedin\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-email\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u7522\u54c1\u5716\u8b5c \u9996\u9801 \u9ede\u64ca\u5716\u7247\u4ee5 PDF \u6a94\u6848\u700f\u89bd \u4e0b\u8f09 \u7522\u54c1\u8a0a\u606f Share on facebook Facebook Share on linkedin Linkedin Share on email Email Share on facebook Share on linkedin Share on email<\/p>\n","protected":false},"author":1313,"featured_media":0,"parent":14544,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"folder":[71],"class_list":["post-18632","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/pages\/18632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/users\/1313"}],"replies":[{"embeddable":true,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/comments?post=18632"}],"version-history":[{"count":5,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/pages\/18632\/revisions"}],"predecessor-version":[{"id":18659,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/pages\/18632\/revisions\/18659"}],"up":[{"embeddable":true,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/pages\/14544"}],"wp:attachment":[{"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/media?parent=18632"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"http:\/\/www.taiwansemi.com\/zh_tw\/wp-json\/wp\/v2\/folder?post=18632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}